{"id":45676,"date":"2023-10-18T13:05:44","date_gmt":"2023-10-18T13:05:44","guid":{"rendered":"https:\/\/staging2.navori.com\/?page_id=45676"},"modified":"2025-11-06T15:08:15","modified_gmt":"2025-11-06T15:08:15","slug":"terms-of-services","status":"publish","type":"page","link":"https:\/\/navori.com\/fr\/terms-of-services\/","title":{"rendered":"Conditions G\u00e9n\u00e9rales \u2013 Navori"},"content":{"rendered":"<section class=\"vc_section term-and-condition\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  page-title\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>CONDITIONS D'UTILISATION DE NAVORI<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Derni\u00e8re mise \u00e0 jour<\/strong>: 23\/07\/2024<\/p>\n<p>Les pr\u00e9sentes Conditions de services (les \u201cConditions\u201d) sont conclues entre l'entit\u00e9 identifi\u00e9e dans un Formulaire de commande ou qui re\u00e7oit un Code d'activation d'un Revendeur (\u201cClient\u201d ; \u201cvous\u201d) et l'Entit\u00e9 contractante Navori. Ces Conditions entrent en vigueur (i) \u00e0 l'achat de la Licence du Logiciel Navori par le biais d'un Formulaire de Commande ; (ii) \u00e0 l'acceptation des Conditions par le Client ou (iii) \u00e0 l'activation ou \u00e0 l'acc\u00e8s aux Services Navori par le Client, selon la premi\u00e8re \u00e9ventualit\u00e9 (la \u201cDate d'Entr\u00e9e en Vigueur\u201d). Vous acceptez et comprenez que ces Conditions sont l\u00e9galement contraignantes. Si vous \u00eates en d\u00e9saccord avec ces Conditions, vous ne pouvez pas utiliser les Services Navori. (Individuellement une \u201cPartie\u201d, et collectivement les \u201cParties\u201d en vertu de ces Conditions).<\/p>\n<p>Nonobstant toute disposition contraire dans les pr\u00e9sentes Conditions, si vous acc\u00e9dez aux Services Navori avec un Code d'activation fourni par un Revendeur, les conditions financi\u00e8res \u00e9nonc\u00e9es dans votre entente avec votre Revendeur ont pr\u00e9s\u00e9ance sur les pr\u00e9sentes Conditions, et toute obligation de paiement ou de remboursement sera directement entre le Client et le Revendeur, conform\u00e9ment \u00e0 une telle entente. Si vous avez sign\u00e9 une variante hors ligne de ces Conditions pour l'utilisation des Services Navori, ces Conditions ci-dessous ne s'appliquent pas \u00e0 vous, et vos conditions hors ligne r\u00e9gissent votre utilisation des Services Navori.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>1.<strong>PR\u00c9AMBULE<\/strong><\/h4>\n<p>CONSID\u00c9RANT que le vendeur est propri\u00e9taire d'un logiciel et de sa documentation associ\u00e9e et qu'il offre un service comprenant l'utilisation de son logiciel ainsi que l'h\u00e9bergement et la maintenance.<\/p>\n<p>CONSIDERANT que le client a l'intention d'utiliser les services du vendeur.<\/p>\n<p>CONSIDERANT que le Vendeur souhaite accorder au Client un service non exclusif et non transf\u00e9rable (\u00e0 l'exception des transferts aux Clients express\u00e9ment autoris\u00e9s par les pr\u00e9sentes) comprenant certains de ses Programmes sur le Territoire, et que le Client souhaite accepter une telle Licence conform\u00e9ment aux termes et conditions des pr\u00e9sentes.<\/p>\n<p>C'est pourquoi, en consid\u00e9ration des promesses et des engagements mutuels contenus dans le pr\u00e9sent document, et pour d'autres raisons valables, dont la r\u00e9ception et la suffisance sont reconnues par la pr\u00e9sente, les parties conviennent de ce qui suit :<\/p>\n<p>Le pr\u00e9sent contrat entre en vigueur entre le client et le vendeur \u00e0 compter de la date d'acceptation du pr\u00e9sent contrat par le client.<\/p>\n<ol>\n<li><strong>PREMABLE<\/strong><br \/>\nLe pr\u00e9ambule est r\u00e9put\u00e9 faire partie int\u00e9grante du pr\u00e9sent accord.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>2. <strong>HORAIRES<\/strong><\/h4>\n<p>L'annexe suivante, jointe au pr\u00e9sent accord, en fait partie int\u00e9grante :<\/p>\n<p>ANNEXE A, INTERPR\u00c9TATION<\/p>\n<p>ANNEXE B, ACCORD DE NIVEAU DE SERVICE<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>3. <strong>SERVICES ACHET\u00c9S<\/strong><\/h4>\n<p>Le vendeur met les services achet\u00e9s, tels que d\u00e9finis \u00e0 l'annexe C, \u00e0 la disposition du client conform\u00e9ment au pr\u00e9sent contrat et aux bons de commande correspondants pendant la dur\u00e9e de l'abonnement. Le client convient que les achats effectu\u00e9s en vertu des pr\u00e9sentes ne d\u00e9pendent pas de la livraison de fonctionnalit\u00e9s ou de caract\u00e9ristiques futures, ni de commentaires publics, oraux ou \u00e9crits, formul\u00e9s par le vendeur au sujet de fonctionnalit\u00e9s ou de caract\u00e9ristiques futures.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>4.<strong>UTILISATION DES SERVICES<\/strong><\/h2>\n<ol>\n<li><strong>Nos responsabilit\u00e9s<\/strong> Le vendeur s'engage \u00e0 : (i) fournir au Client une assistance en ligne pour les Services achet\u00e9s, sans frais suppl\u00e9mentaires tels que d\u00e9finis dans l'Annexe C, et\/ou une assistance am\u00e9lior\u00e9e si elle est achet\u00e9e s\u00e9par\u00e9ment, (ii) d\u00e9ployer des efforts commercialement raisonnables pour rendre les Services achet\u00e9s disponibles 24 heures sur 24, 7 jours sur 7, \u00e0 l'exception de : (b) toute indisponibilit\u00e9 caus\u00e9e par des circonstances \u00e9chappant \u00e0 notre contr\u00f4le raisonnable, notamment les cas de force majeure, les actes de gouvernement, les inondations, les incendies, les tremblements de terre, les troubles civils, les actes de terrorisme, les gr\u00e8ves ou autres probl\u00e8mes sociaux, ou les d\u00e9faillances ou retards des fournisseurs d'acc\u00e8s \u00e0 Internet, et (iii) fournir les services achet\u00e9s uniquement en conformit\u00e9 avec les lois et r\u00e9glementations gouvernementales en vigueur.<\/li>\n<li><strong>Responsabilit\u00e9s des clients<\/strong> . Le client (i) est responsable du respect du pr\u00e9sent contrat par les utilisateurs, (ii) est seul responsable de l'exactitude, de la qualit\u00e9, de l'int\u00e9grit\u00e9 et de la l\u00e9galit\u00e9 des donn\u00e9es du client et des moyens par lesquels il a acquis ces donn\u00e9es, (iii) d\u00e9ploie des efforts commercialement raisonnables pour emp\u00eacher l'acc\u00e8s ou l'utilisation non autoris\u00e9s des services et notifie rapidement au vendeur tout acc\u00e8s ou utilisation non autoris\u00e9, et (iv) n'utilise les services que conform\u00e9ment au guide de l'utilisateur et aux lois et r\u00e9glementations gouvernementales en vigueur. Le client n'utilisera pas les services pour stocker ou transmettre du mat\u00e9riel contrefait, diffamatoire ou autrement ill\u00e9gal ou d\u00e9lictueux, ou pour stocker ou transmettre du mat\u00e9riel en violation des droits de confidentialit\u00e9 de tiers, (a) utiliser les services pour stocker ou transmettre des codes malveillants, (b) interf\u00e9rer avec ou perturber l'int\u00e9grit\u00e9 ou la performance des services ou des donn\u00e9es de tiers qu'ils contiennent, ou (c) tenter d'obtenir un acc\u00e8s non autoris\u00e9 aux services ou \u00e0 leurs syst\u00e8mes ou r\u00e9seaux connexes.<\/li>\n<li><strong>Limites d'utilisation<\/strong> Les services peuvent \u00eatre soumis \u00e0 d'autres limitations, telles que, par exemple, des limites sur l'espace de stockage du disque, sur le nombre d'appels que le client est autoris\u00e9 \u00e0 effectuer \u00e0 partir de l'interface de programmation d'applications du vendeur.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>5. REDEVANCES ET PAIEMENT DES SERVICES ACHET\u00c9S<\/h4>\n<ol>\n<li><strong>Frais d'utilisation<\/strong> Le client doit payer tous les frais sp\u00e9cifi\u00e9s dans tous les bons de commande en vertu des pr\u00e9sentes. Les frais sont indiqu\u00e9s et payables dans la devise dans laquelle le devis a \u00e9t\u00e9 \u00e9tabli. Les frais sont bas\u00e9s sur les services achet\u00e9s et non sur l'utilisation r\u00e9elle, (iii) les obligations de paiement ne sont pas annulables et les frais pay\u00e9s ne sont pas remboursables, et (iv) le nombre d'abonnements d'utilisateur achet\u00e9s ne peut pas \u00eatre r\u00e9duit pendant la dur\u00e9e de l'abonnement indiqu\u00e9e sur le bon de commande.<br \/>\nLes frais d'abonnement de l'utilisateur sont bas\u00e9s sur des p\u00e9riodes annuelles qui commencent \u00e0 la date de d\u00e9but de l'abonnement et \u00e0 chaque anniversaire mensuel de celui-ci ; par cons\u00e9quent, les frais d'abonnement de l'utilisateur sont calcul\u00e9s sur la base de p\u00e9riodes annuelles.<\/li>\n<li><strong>Facturation et paiement<\/strong> . Le client fournira au vendeur ses coordonn\u00e9es ou un bon de commande valide ou un autre document raisonnablement acceptable par le vendeur.<\/li>\n<li><strong>Frais de retard<\/strong> . Si des frais ne sont pas re\u00e7us du client \u00e0 la date d'\u00e9ch\u00e9ance, alors, \u00e0 notre discr\u00e9tion, (a) ces frais peuvent produire des int\u00e9r\u00eats de retard au taux de 1,5% du solde impay\u00e9 par mois, ou au taux maximum autoris\u00e9 par la loi, le taux le plus bas \u00e9tant retenu, \u00e0 partir de la date \u00e0 laquelle le paiement \u00e9tait d\u00fb jusqu'\u00e0 la date de paiement, et\/ou (b) le vendeur peut conditionner les renouvellements d'abonnement et les bons de commande futurs \u00e0 des conditions de paiement plus courtes.<\/li>\n<li><strong>Suspension du service et acc\u00e9l\u00e9ration<\/strong> Si un montant d\u00fb par le client en vertu du pr\u00e9sent contrat ou de tout autre contrat de services est en souffrance depuis 10 jours ou plus, le vendeur peut, sans limiter ses autres droits et recours, acc\u00e9l\u00e9rer les obligations du client en mati\u00e8re de frais impay\u00e9s en vertu de ces contrats, de sorte que toutes ces obligations deviennent imm\u00e9diatement exigibles et payables, et suspendre nos services au client jusqu'\u00e0 ce que ces montants soient pay\u00e9s en totalit\u00e9.<\/li>\n<li><strong>Imp\u00f4ts<\/strong> Sauf indication contraire, les frais ne comprennent pas les taxes, les pr\u00e9l\u00e8vements, les droits ou les \u00e9valuations gouvernementales similaires de quelque nature que ce soit. Les clients sont responsables du paiement de toutes les taxes associ\u00e9es aux achats qu'ils effectuent dans le cadre des pr\u00e9sentes.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>6. DROITS DE PROPRI\u00c9T\u00c9<\/h4>\n<ol>\n<li><strong>R\u00e9serve de droits. <\/strong> Sous r\u00e9serve des droits limit\u00e9s express\u00e9ment accord\u00e9s par les pr\u00e9sentes, le vendeur se r\u00e9serve tous les droits, titres et int\u00e9r\u00eats relatifs aux services, y compris tous les droits de propri\u00e9t\u00e9 intellectuelle y aff\u00e9rents. Aucun droit n'est accord\u00e9 au client en vertu des pr\u00e9sentes, \u00e0 l'exception des droits express\u00e9ment \u00e9nonc\u00e9s dans les pr\u00e9sentes.<\/li>\n<li><strong>Reconnaissance des droits de propri\u00e9t\u00e9 du vendeur<\/strong> . Le client reconna\u00eet par la pr\u00e9sente que le vendeur est le seul propri\u00e9taire de tous les droits, titres et int\u00e9r\u00eats relatifs aux produits, ainsi qu'\u00e0 tout logiciel, programme ou documentation s'y rapportant, tels que tout mat\u00e9riel promotionnel, marketing et publicitaire, et toute copie de celui-ci, ainsi que tous les droits d'auteur, secrets commerciaux, brevets, marques commerciales et autres droits de propri\u00e9t\u00e9 intellectuelle ou industrielle li\u00e9s d'une mani\u00e8re ou d'une autre aux produits, Le client c\u00e8de irr\u00e9vocablement au vendeur tous les droits, titres et int\u00e9r\u00eats potentiels du client dans tous les changements, modifications, am\u00e9liorations, perfectionnements, inventions et d\u00e9couvertes relatifs au produit, \u00e0 son d\u00e9veloppement, \u00e0 son utilisation ou \u00e0 sa commercialisation, le cas \u00e9ch\u00e9ant ;<\/li>\n<li><strong>Restrictions<\/strong> . Le client n'autorisera aucun tiers \u00e0 cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es bas\u00e9es sur les services, \u00e0 faire de l'ing\u00e9nierie inverse sur les services, \u00e0 acc\u00e9der aux services pour cr\u00e9er un produit ou un service concurrent, ou \u00e0 copier des caract\u00e9ristiques, des fonctions ou des graphiques des services.<\/li>\n<li><strong>Propri\u00e9t\u00e9 des donn\u00e9es des clients<\/strong> Entre le Vendeur et le Client, le Client d\u00e9tient exclusivement tous les droits, titres et int\u00e9r\u00eats relatifs \u00e0 l'ensemble des Donn\u00e9es du Client.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>7. LA CONFIDENTIALIT\u00c9<\/h4>\n<ol>\n<li><strong>D\u00e9finition de l'information confidentielle<\/strong> Dans le cadre des pr\u00e9sentes, on entend par \u201cinformations confidentielles\u201d toutes les informations confidentielles divulgu\u00e9es par une partie (\u201dpartie divulgatrice\u201d) \u00e0 l'autre partie (\u201dpartie destinataire\u201d), oralement ou par \u00e9crit, qui sont d\u00e9sign\u00e9es comme confidentielles ou qui devraient raisonnablement \u00eatre consid\u00e9r\u00e9es comme confidentielles compte tenu de la nature de l'information et des circonstances de la divulgation. Les informations confidentielles du client comprennent les donn\u00e9es du client ; nos informations confidentielles comprennent les services ; et les informations confidentielles de chaque partie comprennent les termes et conditions du pr\u00e9sent accord et tous les formulaires de commande, ainsi que les plans d'affaires et de marketing, la technologie et les informations techniques, les plans et conceptions de produits et les processus d'affaires divulgu\u00e9s par ladite partie. Toutefois, les informations confidentielles (autres que les donn\u00e9es des clients) ne comprennent pas les informations qui (i) sont ou deviennent g\u00e9n\u00e9ralement connues du public sans qu'il y ait eu violation d'une obligation envers la partie divulgatrice, (ii) \u00e9taient connues de la partie destinataire avant leur divulgation par la partie divulgatrice sans qu'il y ait eu violation d'une obligation envers la partie divulgatrice, (iii) sont re\u00e7ues d'un tiers sans qu'il y ait eu violation d'une obligation envers la partie divulgatrice, ou (iv) ont \u00e9t\u00e9 d\u00e9velopp\u00e9es de mani\u00e8re ind\u00e9pendante par la partie destinataire.<\/li>\n<li><strong>Protection des informations confidentielles<\/strong> . Sauf autorisation \u00e9crite contraire de la partie divulgatrice, (i) la partie destinataire doit faire preuve du m\u00eame degr\u00e9 de diligence que celui qu'elle utilise pour prot\u00e9ger la confidentialit\u00e9 de ses propres informations confidentielles de m\u00eame nature (mais en aucun cas d'une diligence moins que raisonnable) pour ne pas divulguer ou utiliser les informations confidentielles de la partie divulgatrice \u00e0 des fins qui sortent du cadre du pr\u00e9sent accord, et (ii) la partie destinataire limitera l'acc\u00e8s aux informations confidentielles de la partie divulgatrice \u00e0 ses employ\u00e9s, contractants et agents qui ont besoin d'un tel acc\u00e8s \u00e0 des fins compatibles avec le pr\u00e9sent accord et qui ont sign\u00e9 avec la partie destinataire des accords de confidentialit\u00e9 contenant des protections au moins aussi strictes que celles pr\u00e9vues par le pr\u00e9sent accord.<\/li>\n<li><strong>Protection des donn\u00e9es des clients<\/strong> Sans pr\u00e9judice de ce qui pr\u00e9c\u00e8de, le vendeur doit maintenir des mesures de protection administratives, physiques et techniques appropri\u00e9es pour assurer la s\u00e9curit\u00e9, la confidentialit\u00e9 et l'int\u00e9grit\u00e9 des donn\u00e9es du client.<\/li>\n<li><strong>Divulgation obligatoire<\/strong> La partie destinataire peut divulguer des informations confidentielles de la partie divulgatrice si elle y est contrainte par la loi, \u00e0 condition que la partie destinataire donne \u00e0 la partie divulgatrice un pr\u00e9avis de cette divulgation forc\u00e9e (dans la mesure o\u00f9 la loi le permet) et une assistance raisonnable, aux frais de la partie divulgatrice, si la partie divulgatrice souhaite contester la divulgation. Si la partie destinataire est contrainte par la loi de divulguer les informations confidentielles de la partie divulgatrice dans le cadre d'une proc\u00e9dure civile \u00e0 laquelle la partie divulgatrice est partie, et si la partie divulgatrice ne conteste pas la divulgation, la partie divulgatrice remboursera \u00e0 la partie destinataire le co\u00fbt raisonnable de la compilation et de la fourniture d'un acc\u00e8s s\u00e9curis\u00e9 \u00e0 ces informations confidentielles.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>8. GARANTIES ET CLAUSES DE NON-RESPONSABILIT\u00c9<\/h4>\n<ol>\n<li><strong>Nos garanties<\/strong> Le vendeur garantit que (i) les services fonctionneront mat\u00e9riellement conform\u00e9ment au guide de l'utilisateur, la fonctionnalit\u00e9 des services ne sera pas mat\u00e9riellement r\u00e9duite pendant la dur\u00e9e de l'abonnement. En cas de violation de l'une ou l'autre de ces garanties, le recours exclusif du client sera celui pr\u00e9vu \u00e0 l'article 11.3 (R\u00e9siliation pour motif) et \u00e0 l'article 11.4 (Remboursement ou paiement en cas de r\u00e9siliation) ci-dessous.<\/li>\n<li><strong>Garanties mutuelles<\/strong> Chaque partie d\u00e9clare et garantit qu'elle a le pouvoir l\u00e9gal de conclure le pr\u00e9sent accord et qu'elle ne transmettra \u00e0 l'autre partie aucun code malveillant (\u00e0 l'exception des codes malveillants pr\u00e9c\u00e9demment transmis \u00e0 la partie garante par l'autre partie).<\/li>\n<li><strong>Conditions de garantie<\/strong><br \/>\nToute garantie du vendeur n'est effective que si toutes les conditions suivantes sont remplies :<\/p>\n<ol>\n<li>Le client a pleinement respect\u00e9 toutes les obligations de paiement relatives aux produits et, d'une mani\u00e8re g\u00e9n\u00e9rale, toutes ses obligations contractuelles et l\u00e9gales.<\/li>\n<li>Le client a envoy\u00e9 une notification \u00e9crite par l'interm\u00e9diaire du syst\u00e8me d'assistance du vendeur dans les cinq (5) jours ouvrables suivant la d\u00e9couverte du probl\u00e8me et a demand\u00e9 une action de la part du vendeur.<\/li>\n<li>Le vendeur a eu la possibilit\u00e9 d'inspecter le produit et est convaincu que le produit ne r\u00e9pond pas aux sp\u00e9cifications garanties.<\/li>\n<li>Le produit n'a pas \u00e9t\u00e9 utilis\u00e9, entretenu, modifi\u00e9, alt\u00e9r\u00e9, install\u00e9 ou int\u00e9gr\u00e9 contrairement aux instructions, directives ou recommandations du vendeur, ou contrairement aux normes et standards actuels de l'industrie ; les produits n'ont pas fait l'objet d'une mauvaise utilisation, d'un test inappropri\u00e9 ou d'une mauvaise manipulation.<\/li>\n<\/ol>\n<\/li>\n<li><strong>Clause de non-responsabilit\u00e9<\/strong> SAUF DISPOSITION EXPRESSE DANS LES PRESENTES, AUCUNE DES PARTIES NE DONNE DE GARANTIE DE QUELQUE NATURE QUE CE SOIT, EXPRESSE, IMPLICITE, LEGALE OU AUTRE, ET CHAQUE PARTIE REJETTE SPECIFIQUEMENT TOUTE GARANTIE IMPLICITE, Y COMPRIS TOUTE GARANTIE DE QUALITE MARCHANDE OU D'ADEQUATION A UN USAGE PARTICULIER, DANS TOUTE LA MESURE AUTORISEE PAR LA LOI APPLICABLE.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>9. INDEMNISATION MUTUELLE<\/h4>\n<ol>\n<li><strong>Indemnisation par le vendeur<\/strong> Le Vendeur s'engage \u00e0 d\u00e9fendre le Client contre toute r\u00e9clamation, demande, poursuite ou proc\u00e9dure (\u201dR\u00e9clamation\u201d) faite ou intent\u00e9e contre le Client par un tiers all\u00e9guant que l'utilisation des Services (\u00e0 l'exclusion des donn\u00e9es de Contenu), telle que permise par les pr\u00e9sentes, viole ou d\u00e9tourne les droits de propri\u00e9t\u00e9 intellectuelle d'un tiers, et \u00e0 indemniser le Client pour tout dommage finalement accord\u00e9 et pour les frais d'avocat raisonnables encourus par le Client dans le cadre d'une telle R\u00e9clamation ; \u00e0 condition que le client (a) donne rapidement au vendeur une notification \u00e9crite de la r\u00e9clamation ; (b) donne au vendeur le contr\u00f4le exclusif de la d\u00e9fense et du r\u00e8glement de la r\u00e9clamation (\u00e0 condition que le vendeur ne puisse pas r\u00e9gler une r\u00e9clamation \u00e0 moins que le r\u00e8glement ne lib\u00e8re inconditionnellement le client de toute responsabilit\u00e9) ; et (c) fournisse au vendeur toute l'assistance raisonnable, aux frais du vendeur.<\/li>\n<li><strong>Indemnisation par le client<\/strong> Le Client d\u00e9fendra le Vendeur contre toute r\u00e9clamation faite ou port\u00e9e contre le Vendeur par un tiers all\u00e9guant que les Donn\u00e9es du Client, ou l'utilisation par le Client des Services en violation du pr\u00e9sent Accord, viole ou d\u00e9tourne les droits de propri\u00e9t\u00e9 intellectuelle d'un tiers ou viole la loi applicable, et indemnisera le Vendeur pour tous les dommages-int\u00e9r\u00eats finalement accord\u00e9s et pour les frais d'avocat raisonnables encourus par le Vendeur dans le cadre d'une telle r\u00e9clamation ; \u00e0 condition que le vendeur (a) informe rapidement le client par \u00e9crit de la r\u00e9clamation ; (b) donne au client le contr\u00f4le exclusif de la d\u00e9fense et du r\u00e8glement de la r\u00e9clamation (\u00e0 condition que le client ne puisse pas r\u00e9gler une r\u00e9clamation \u00e0 moins que le r\u00e8glement ne lib\u00e8re inconditionnellement le vendeur de toute responsabilit\u00e9) ; et (c) fournisse au client toute l'assistance raisonnable, aux frais du vendeur.<\/li>\n<li><strong>Rem\u00e8de exclusif<\/strong> . La pr\u00e9sente section 9 (Indemnisation mutuelle) \u00e9nonce la seule responsabilit\u00e9 de la partie indemnisante \u00e0 l'\u00e9gard de l'autre partie et le recours exclusif de la partie indemnis\u00e9e \u00e0 l'encontre de l'autre partie pour tout type de r\u00e9clamation d\u00e9crite dans la pr\u00e9sente section.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>10. LIMITATION DE LA RESPONSABILIT\u00c9<\/h4>\n<ol>\n<li><strong>Limitation de la responsabilit\u00e9<\/strong> EN AUCUN CAS, LA RESPONSABILIT\u00c9 GLOBALE DE L'UNE OU L'AUTRE PARTIE D\u00c9COULANT DU PR\u00c9SENT ACCORD OU S'Y RAPPORTANT, QUE CE SOIT DANS LE CADRE D'UN CONTRAT, D'UN D\u00c9LIT OU DE TOUTE AUTRE TH\u00c9ORIE DE LA RESPONSABILIT\u00c9, NE D\u00c9PASSERA LE MONTANT TOTAL PAY\u00c9 PAR LE CLIENT EN VERTU DU PR\u00c9SENT ACCORD OU, EN CE QUI CONCERNE UN INCIDENT UNIQUE, LE MONTANT LE MOINS \u00c9LEV\u00c9 ENTRE $10 000 ET LE MONTANT PAY\u00c9 PAR LE CLIENT EN VERTU DU PR\u00c9SENT ACCORD AU COURS DES 12 MOIS PR\u00c9C\u00c9DANT L'INCIDENT. CE QUI PRECEDE NE LIMITE PAS LES OBLIGATIONS DE PAIEMENT DU CLIENT AU TITRE DE LA SECTION 5 (REDEVANCES ET PAIEMENT DES SERVICES ACHETES).<\/li>\n<li><strong>Exclusion des dommages cons\u00e9cutifs et connexes<\/strong> . EN AUCUN CAS, L'UNE OU L'AUTRE DES PARTIES NE SERA RESPONSABLE ENVERS L'AUTRE PARTIE DE TOUTE PERTE DE PROFITS OU DE REVENUS OU DE TOUT DOMMAGE INDIRECT, SP\u00c9CIAL, ACCESSOIRE, CONS\u00c9CUTIF, COUVERT OU PUNITIF, QUELLE QU'EN SOIT LA CAUSE, QUE CE SOIT DANS LE CADRE D'UN CONTRAT, D'UN D\u00c9LIT OU DE TOUTE AUTRE TH\u00c9ORIE DE LA RESPONSABILIT\u00c9, ET QUE LA PARTIE AIT \u00c9T\u00c9 INFORM\u00c9E OU NON DE LA POSSIBILIT\u00c9 DE TELS DOMMAGES. LA CLAUSE DE NON-RESPONSABILIT\u00c9 QUI PR\u00c9C\u00c8DE NE S'APPLIQUE PAS DANS LA MESURE O\u00d9 LA LOI APPLICABLE L'INTERDIT.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>11. DUR\u00c9E ET R\u00c9SILIATION<\/h4>\n<ol>\n<li><strong>Dur\u00e9e de l'accord<\/strong> Le pr\u00e9sent accord entre en vigueur \u00e0 la date \u00e0 laquelle le client l'accepte et se poursuit jusqu'\u00e0 ce que tous les abonnements d'utilisateur accord\u00e9s conform\u00e9ment au pr\u00e9sent accord aient expir\u00e9 ou aient \u00e9t\u00e9 r\u00e9sili\u00e9s.<\/li>\n<li><strong>Dur\u00e9e des abonnements d'utilisateur achet\u00e9s<\/strong> Les abonnements d'utilisateur achet\u00e9s par le client (\u201cabonnement d'utilisateur\u201d) commencent \u00e0 la date de d\u00e9but sp\u00e9cifi\u00e9e dans le bon de commande applicable et se poursuivent pendant la dur\u00e9e d'abonnement sp\u00e9cifi\u00e9e dans ce bon de commande. Sauf indication contraire dans le bon de commande applicable, tous les abonnements d'utilisateur sont automatiquement renouvel\u00e9s pour des p\u00e9riodes suppl\u00e9mentaires \u00e9gales \u00e0 la dur\u00e9e de l'abonnement arrivant \u00e0 expiration ou \u00e0 un an (la dur\u00e9e la plus courte \u00e9tant retenue), sauf si l'une des parties notifie \u00e0 l'autre un avis de non-renouvellement au moins 30 jours avant la fin de la dur\u00e9e de l'abonnement concern\u00e9. Le prix \u00e0 l'unit\u00e9 pendant une telle p\u00e9riode de renouvellement sera le m\u00eame que pendant la p\u00e9riode pr\u00e9c\u00e9dente, \u00e0 moins que le vendeur n'ait notifi\u00e9 par \u00e9crit au client une augmentation de prix au moins 30 jours avant la fin de la p\u00e9riode pr\u00e9c\u00e9dente, auquel cas l'augmentation de prix prendra effet au moment du renouvellement et par la suite. Toute augmentation de prix ne doit pas d\u00e9passer l'inflation +7% par rapport au prix des services concern\u00e9s au cours de la p\u00e9riode d'abonnement imm\u00e9diatement pr\u00e9c\u00e9dente, sauf si le prix de cette p\u00e9riode pr\u00e9c\u00e9dente a \u00e9t\u00e9 d\u00e9sign\u00e9 dans le bon de commande concern\u00e9 comme promotionnel ou unique.<\/li>\n<li><strong>Licenciement pour motif grave<\/strong> Une partie peut r\u00e9silier le pr\u00e9sent accord pour un motif valable : moyennant un pr\u00e9avis \u00e9crit de 30 jours adress\u00e9 \u00e0 l'autre partie en cas de violation substantielle, si cette violation n'est pas corrig\u00e9e \u00e0 l'expiration de ce d\u00e9lai, ou si l'autre partie fait l'objet d'une demande de mise en faillite ou de toute autre proc\u00e9dure relative \u00e0 l'insolvabilit\u00e9, \u00e0 la mise sous s\u00e9questre, \u00e0 la liquidation ou \u00e0 la cession au profit de cr\u00e9anciers.<\/li>\n<li><strong>Remboursement ou paiement en cas de r\u00e9siliation<\/strong> . En cas de r\u00e9siliation motiv\u00e9e par le client, le vendeur rembourse au client les frais pay\u00e9s d'avance couvrant le reste de la dur\u00e9e de tous les abonnements apr\u00e8s la date effective de r\u00e9siliation. En cas de r\u00e9siliation motiv\u00e9e par le vendeur, le client doit payer tous les frais impay\u00e9s couvrant le reste de la dur\u00e9e de tous les bons de commande apr\u00e8s la date d'effet de la r\u00e9siliation. En aucun cas, la r\u00e9siliation ne lib\u00e8re le client de l'obligation de payer au prorata les redevances non contest\u00e9es dues au vendeur pour la p\u00e9riode pr\u00e9c\u00e9dant la date effective de r\u00e9siliation.<\/li>\n<li><strong>Retour des donn\u00e9es des clients<\/strong> Sur demande du Client formul\u00e9e dans les 30 jours suivant la date effective de r\u00e9siliation d'un abonnement aux Services achet\u00e9s, le Vendeur mettra \u00e0 la disposition du Client pour t\u00e9l\u00e9chargement un fichier de Donn\u00e9es de contenu du Client dans leur format d'origine. Apr\u00e8s cette p\u00e9riode de 30 jours, le Vendeur n'aura aucune obligation de maintenir ou de fournir les Donn\u00e9es du Client et devra par la suite, sauf interdiction l\u00e9gale, supprimer toutes les Donn\u00e9es du Client dans nos syst\u00e8mes ou autrement en notre possession ou sous notre contr\u00f4le.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>12. AVEC QUI LE CLIENT PASSE UN CONTRAT, AVIS, DROIT APPLICABLE ET JURIDICTION<\/h4>\n<ol>\n<li><strong>G\u00e9n\u00e9ral<\/strong> La personne avec laquelle le client passe un contrat dans le cadre du pr\u00e9sent accord, la personne \u00e0 laquelle le client doit adresser des notifications dans le cadre du pr\u00e9sent accord, le droit applicable \u00e0 tout proc\u00e8s d\u00e9coulant du pr\u00e9sent accord ou en rapport avec celui-ci, et les tribunaux habilit\u00e9s \u00e0 statuer sur un tel proc\u00e8s, d\u00e9pendent du lieu o\u00f9 le client est domicili\u00e9.<br \/>\n<table>\n<tbody>\n<tr>\n<td>Les clients sont en train de contracter avec :<\/td>\n<td>Les avis doivent \u00eatre adress\u00e9s \u00e0<\/td>\n<td>La loi applicable est la suivante :<\/td>\n<td>Les tribunaux ayant une comp\u00e9tence exclusive sont :<\/td>\n<\/tr>\n<tr>\n<td>Navori SA<br \/>\nAvenue mon repos 22<br \/>\n1005 Lausanne<br \/>\nSuisse<\/td>\n<td>Service juridique<\/td>\n<td>Suisse<\/td>\n<td>Canton de Vaud<\/td>\n<\/tr>\n<tr>\n<td>Navori Inc<br \/>\nBureau 710- 1000 Sherbrooke Ouest. H3A 3G4 Montr\u00e9al<br \/>\nCanada<\/td>\n<td>Service juridique<\/td>\n<td>Qu\u00e9bec, Canada<\/td>\n<td>Montr\u00e9al Canada<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/li>\n<li><strong>Modalit\u00e9s de notification<\/strong> Sauf indication contraire dans le pr\u00e9sent accord, tous les avis, permissions et approbations pr\u00e9vus par le pr\u00e9sent accord sont donn\u00e9s par \u00e9crit et sont r\u00e9put\u00e9s avoir \u00e9t\u00e9 remis en mains propres.<\/li>\n<li><strong>Modalit\u00e9s de notification<\/strong> Sauf indication contraire dans le pr\u00e9sent accord, tous les avis, permissions et approbations pr\u00e9vus par le pr\u00e9sent accord sont donn\u00e9s par \u00e9crit et sont r\u00e9put\u00e9s avoir \u00e9t\u00e9 remis en mains propres.<\/li>\n<li><strong>Accord sur la loi applicable et la juridiction<\/strong> Chaque partie accepte la loi applicable ci-dessus, sans tenir compte des r\u00e8gles de choix ou de conflit de lois, et la comp\u00e9tence exclusive des tribunaux applicables ci-dessus.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>13. DISPOSITIONS G\u00c9N\u00c9RALES<\/h4>\n<ol>\n<li>Relation entre les parties. Les parties sont des entrepreneurs ind\u00e9pendants. Le pr\u00e9sent accord ne cr\u00e9e pas de relation de partenariat, de franchise, d'entreprise commune, d'agence, de fiducie ou d'emploi entre les parties.<\/li>\n<li>Renonciation et recours cumulatifs. Aucun manquement ou retard de l'une ou l'autre partie dans l'exercice d'un droit en vertu du pr\u00e9sent accord ne constitue une renonciation \u00e0 ce droit. Sauf mention expresse dans le pr\u00e9sent document, les recours pr\u00e9vus dans le pr\u00e9sent document s'ajoutent \u00e0 tout autre recours d'une partie, en droit ou en \u00e9quit\u00e9, et ne l'excluent pas.<\/li>\n<li>Divisibilit\u00e9. Si une disposition du pr\u00e9sent accord est jug\u00e9e contraire \u00e0 la loi par un tribunal comp\u00e9tent, cette disposition sera modifi\u00e9e par le tribunal et interpr\u00e9t\u00e9e de mani\u00e8re \u00e0 atteindre au mieux les objectifs de la disposition initiale, dans toute la mesure permise par la loi, et les autres dispositions du pr\u00e9sent accord resteront en vigueur.<\/li>\n<li>Frais d'avocat. Le client doit payer sur demande tous nos honoraires d'avocat raisonnables et autres frais encourus par le vendeur pour recouvrer les frais ou redevances dus au vendeur en vertu du pr\u00e9sent contrat \u00e0 la suite d'une violation par le client de l'article 4.2 (Facturation et paiement).<\/li>\n<li><strong>Affectation<\/strong> Aucune des parties ne peut c\u00e9der ses droits ou obligations en vertu des pr\u00e9sentes, que ce soit par application de la loi ou autrement, sans le consentement \u00e9crit pr\u00e9alable de l'autre partie (qui ne doit pas \u00eatre refus\u00e9 de mani\u00e8re d\u00e9raisonnable). Nonobstant ce qui pr\u00e9c\u00e8de, chaque partie peut c\u00e9der le pr\u00e9sent accord dans son int\u00e9gralit\u00e9 (y compris tous les formulaires de commande), sans le consentement de l'autre partie, \u00e0 sa soci\u00e9t\u00e9 affili\u00e9e ou dans le cadre d'une fusion, d'une acquisition, d'une r\u00e9organisation d'entreprise ou d'une vente de la totalit\u00e9 ou de la quasi-totalit\u00e9 de ses actifs n'impliquant pas un concurrent direct de l'autre partie.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>14. ANNEXE A, INTERPR\u00c9TATION<\/h4>\n<table>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><strong>Affiliation <\/strong><\/td>\n<td style=\"text-align: left;\">en ce qui concerne une personne (\u201cpremi\u00e8re personne\u201d), d\u00e9signe une personne qui contr\u00f4le directement ou indirectement cette premi\u00e8re personne, ou qui est contr\u00f4l\u00e9e par elle, ou qui est sous contr\u00f4le commun avec elle, le terme \u201ccontr\u00f4le\u201d d\u00e9signant la possession, directement ou indirectement, ou en tant que fiduciaire ou ex\u00e9cuteur, du pouvoir de diriger ou de faire diriger les affaires ou la gestion de la personne, que ce soit par la propri\u00e9t\u00e9 de titres avec droit de vote, en tant que fiduciaire ou ex\u00e9cuteur, par contrat ou d'une autre mani\u00e8re ; et (ii) en ce qui concerne le client, comprend \u00e9galement une personne pour laquelle le client d\u00e9tient directement ou indirectement au moins 50% des actions participantes de cette personne, \u00e0 condition toutefois qu'aux fins du pr\u00e9sent accord, les soci\u00e9t\u00e9s de portefeuille du client ne soient pas consid\u00e9r\u00e9es comme des soci\u00e9t\u00e9s affili\u00e9es du client.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Semaine ou jour ouvrable<\/strong><\/td>\n<td style=\"text-align: left;\">signifie du lundi au vendredi, \u00e0 l'exception des jours f\u00e9ri\u00e9s en Suisse et au Canada.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>D\u00e9faut critique <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe un d\u00e9faut qui rend le logiciel sous licence inop\u00e9rant et qui a un impact critique sur le fonctionnement du logiciel sous licence. Les d\u00e9fauts critiques doivent pouvoir \u00eatre reproduits par le vendeur.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Client <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe la soci\u00e9t\u00e9 ou autre entit\u00e9 juridique pour laquelle le client accepte le pr\u00e9sent accord et les soci\u00e9t\u00e9s affili\u00e9es \u00e0 cette soci\u00e9t\u00e9 ou entit\u00e9.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Client <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe le client.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Donn\u00e9es sur les clients <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe toutes les donn\u00e9es ou informations \u00e9lectroniques soumises par le client aux services achet\u00e9s.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>D\u00e9faut <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe une condition du logiciel sous licence signal\u00e9e au vendeur qui fait qu'une version du logiciel sous licence ne fonctionne pas conform\u00e9ment aux sp\u00e9cifications techniques du logiciel sous licence et de la documentation. Les d\u00e9fauts doivent pouvoir \u00eatre reproduits par le vendeur.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Affichage dynamique <\/strong><\/td>\n<td style=\"text-align: left;\">Le secteur de la cr\u00e9ation, de la gestion et de la diffusion de contenus par le biais d'\u00e9crans num\u00e9riques connect\u00e9s.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Assistance \u00e9lectronique <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe l'assistance fournie par le syst\u00e8me de tickets de maintenance du vendeur.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Activation de la licence <\/strong><\/td>\n<td style=\"text-align: left;\">signifie l'installation et l'enregistrement du programme sur un ordinateur, un appareil ou sur tout mat\u00e9riel sur lequel il s'ex\u00e9cute.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Programme de tickets de maintenance <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe un centre de maintenance \u00e9lectronique bas\u00e9 sur l'enregistrement des tickets de maintenance, qui garantit une r\u00e9ponse dans les 24 heures ouvrables et un historique complet de la maintenance.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>D\u00e9faut majeur<\/strong><\/td>\n<td style=\"text-align: left;\">rend les solutions de contournement difficiles ou inefficaces, entra\u00eene une d\u00e9gradation substantielle des performances, emp\u00eache le client d'utiliser une fonction majeure du logiciel sous licence, affecte gravement la fiabilit\u00e9 du logiciel sous licence, ou manque une capacit\u00e9 substantielle n\u00e9cessaire. Les d\u00e9fauts majeurs doivent pouvoir \u00eatre reproduits par le vendeur et signal\u00e9s par le biais du syst\u00e8me de tickets de maintenance.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Code malveillant <\/strong><\/td>\n<td style=\"text-align: left;\">les virus, les vers, les bombes \u00e0 retardement, les chevaux de Troie et autres codes, fichiers, scripts, agents ou programmes nuisibles ou malveillants.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>D\u00e9faut mineur <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe un d\u00e9faut qui provoque une erreur de message ou de document, mais qui n'a pas d'incidence sur le fonctionnement du logiciel sous licence. Des solutions de contournement sont g\u00e9n\u00e9ralement disponibles. Ces d\u00e9fauts peuvent \u00eatre trait\u00e9s par un correctif ou une solution de contournement ou dans la version suivante. Les d\u00e9fauts mineurs doivent pouvoir \u00eatre reproduits par le vendeur.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Nouvelles publications <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe toute nouvelle version du logiciel sous licence.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Formulaire de commande <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe les documents de commande pour les achats effectu\u00e9s dans le cadre des pr\u00e9sentes, y compris leurs avenants, qui sont conclus entre le client et le vendeur de temps \u00e0 autre. Les bons de commande sont r\u00e9put\u00e9s incorpor\u00e9s aux pr\u00e9sentes par r\u00e9f\u00e9rence.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Patch <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe une modification temporaire dans une version de maintenance technique.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Devis <\/strong><\/td>\n<td style=\"text-align: left;\">document officiel \u00e9mis par le Vendeur listant les produits ou services, ainsi que les termes, pr\u00e9requis, date d'expiration et conditions de paiement qui y sont associ\u00e9s.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>R\u00e9solution <\/strong><\/td>\n<td style=\"text-align: left;\">la mise en place d'une solution permanente \u00e0 un d\u00e9faut.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Services <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe les applications et la plate-forme en ligne, bas\u00e9es sur le Web, fournies par le Vendeur via https:\/\/www.saas.navori.com et\/ou d'autres sites Web d\u00e9sign\u00e9s tels que d\u00e9crits dans le Guide de l'utilisateur, qui sont command\u00e9es par le Client dans le cadre d'un Bon de commande, y compris les composants hors ligne associ\u00e9s, mais \u00e0 l'exclusion des applications de tiers.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Demande de services <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe une demande du client au vendeur de fournir une r\u00e9solution ou une cl\u00f4ture concernant un d\u00e9faut.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Applications tierces<\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe les applications en ligne, bas\u00e9es sur le Web, et les produits logiciels hors ligne fournis par des tiers, qui interagissent avec les services et sont identifi\u00e9s comme des applications de tiers.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Niveau 1<\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe le niveau de maintenance initial responsable des probl\u00e8mes de base des clients. Il est synonyme de maintenance de premi\u00e8re ligne, de maintenance de niveau 1, de maintenance frontale, de maintenance de ligne 1 et de divers autres intitul\u00e9s d\u00e9signant des fonctions de maintenance technique de niveau de base.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Niveau 2 <\/strong><\/td>\n<td style=\"text-align: left;\">Niveau de maintenance technique approfondie autre que le niveau I et avec les techniciens et ing\u00e9nieurs les plus exp\u00e9riment\u00e9s sur un produit ou un service particulier.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Marques d\u00e9pos\u00e9es <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe toutes les marques commerciales d\u00e9tenues par le vendeur dans n'importe quel pays \u00e0 la date d'entr\u00e9e en vigueur, qu'elles soient enregistr\u00e9es publiquement ou non, ainsi que toutes les marques commerciales que le vendeur pourrait acqu\u00e9rir pendant la dur\u00e9e du pr\u00e9sent accord.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Limites d'utilisation <\/strong><\/td>\n<td style=\"text-align: left;\">signifie une limitation de 5 Go de stockage par lecteur. Aucune restriction en termes de nombre d'utilisateurs, de dur\u00e9e d'utilisation et de zone g\u00e9ographique.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Guide de l'utilisateur <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe le guide de l'utilisateur en ligne pour les services, accessible via http:\/\/www.saas.navori.com, tel que mis \u00e0 jour de temps \u00e0 autre. Le client reconna\u00eet qu'il a eu la possibilit\u00e9 de consulter le guide de l'utilisateur pendant l'essai gratuit d\u00e9crit \u00e0 l'article 2 (essai gratuit de 30 jours) ci-dessous.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Utilisateurs <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe les personnes autoris\u00e9es par le client \u00e0 utiliser les services, pour lesquelles des abonnements \u00e0 un service ont \u00e9t\u00e9 achet\u00e9s et auxquelles le client (ou le vendeur \u00e0 la demande du client) a fourni des identifiants et des mots de passe. Les utilisateurs peuvent inclure, sans s'y limiter, les employ\u00e9s, consultants, contractants et agents du client, ou les tiers avec lesquels le client fait des affaires.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Vendeur <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe le groupe Navori<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Solution de contournement <\/strong><\/td>\n<td style=\"text-align: left;\">d\u00e9signe une solution temporaire qui r\u00e9tablit la capacit\u00e9 op\u00e9rationnelle du logiciel sous licence, sans compromettre gravement les performances du logiciel sous licence.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>15. ANNEXE B, ACCORD DE NIVEAU DE SERVICE<\/h4>\n<ol>\n<li><strong>PR\u00c9AMBULE <\/strong>Consid\u00e9rant que le pr\u00e9sent contrat a pour objet de d\u00e9finir les conditions dans lesquelles le vendeur fournit au client l'h\u00e9bergement, la maintenance, les mises \u00e0 niveau et les services pour les produits sous licence.<\/li>\n<li><strong>CONTENU DES SERVICES DE MAINTENANCE<\/strong><\/li>\n<\/ol>\n<ol>\n<li><strong>Niveau des services de maintenance<\/strong><br \/>\nLe vendeur fournit au client une maintenance de niveau 1 et de niveau 2.<\/li>\n<li><strong>Conditions de couverture<\/strong><br \/>\n<table>\n<tbody>\n<tr>\n<td><\/td>\n<td>Localisation<\/td>\n<td>Heure locale<\/td>\n<td>Jours ouvrables<\/td>\n<td>Langues<\/td>\n<\/tr>\n<tr>\n<td>Asie<\/td>\n<td>Inde<\/td>\n<td>GMT - 5:30<\/td>\n<td>Du lundi au vendredi<\/td>\n<td>Anglais, hindi<\/td>\n<\/tr>\n<tr>\n<td>Moyen-Orient<\/td>\n<td>Duba\u00ef et Riyad<\/td>\n<td>GMT + 3 et GMT +4<\/td>\n<td>Du dimanche au jeudi<\/td>\n<td>Arabe et anglais<\/td>\n<\/tr>\n<tr>\n<td>L'Europe<\/td>\n<td>Suisse<\/td>\n<td>GMT + 1<\/td>\n<td>Du lundi au vendredi<\/td>\n<td>Anglais, fran\u00e7ais, allemand, espagnol et portugais<\/td>\n<\/tr>\n<tr>\n<td>Am\u00e9rique du Nord<\/td>\n<td>Canada<\/td>\n<td>Heure normale de l'Est<\/td>\n<td>Du lundi au vendredi<\/td>\n<td>Anglais, fran\u00e7ais<\/td>\n<\/tr>\n<tr>\n<td>Am\u00e9rique centrale Am\u00e9rique du Sud<\/td>\n<td>Mexique<\/td>\n<td>Heure normale du Centre<\/td>\n<td>Du lundi au vendredi<\/td>\n<td>Espagnol, portugais et anglais<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Les services de maintenance fournis par le vendeur sont disponibles pendant les heures d'ouverture locales, de 8h30 \u00e0 17h30, les jours ouvrables locaux, du lundi au vendredi, conform\u00e9ment au tableau des fuseaux horaires ci-dessus.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>16. Programme de tickets de maintenance et assistance \u00e9lectronique<\/h2>\n<p>Le temps de r\u00e9ponse et de r\u00e9solution des tickets de maintenance d\u00e9pend de la priorit\u00e9 du ou des articles concern\u00e9s et de la gravit\u00e9 du d\u00e9faut, comme indiqu\u00e9 dans le calendrier suivant :<\/p>\n<p>Le Client doit utiliser le service d'assistance du Programme de tickets de maintenance fourni par le Vendeur. Le service mentionn\u00e9 dans les pr\u00e9sentes permet au client d'obtenir de l'aide pour identifier et trouver les causes d'un d\u00e9faut pr\u00e9sum\u00e9 du logiciel sous licence et pour fournir la solution appropri\u00e9e, l'action corrective ou tout autre contournement de ce d\u00e9faut dans les plus brefs d\u00e9lais.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>17. Fourniture de nouvelles versions du logiciel<\/h4>\n<p>Le vendeur informe le client, d\u00e8s qu'elles sont commercialement disponibles, de l'existence de nouvelles versions du logiciel sous licence et fournit la copie principale de ces derni\u00e8res au client tant que ce dernier fait l'objet d'une commande en cours d'ex\u00e9cution pour des services de maintenance et d'entretien.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>18. Temps de r\u00e9ponse<\/h4>\n<p>Temps de r\u00e9ponse et \u00e9tat d'avancement<\/p>\n<table>\n<tbody>\n<tr>\n<td>Priorit\u00e9 de la demande de service<\/td>\n<td>R\u00e9ponse initiale<\/td>\n<td>\u00c9tat d'avancement des travaux<\/td>\n<td>Objectif de la r\u00e9solution<\/td>\n<\/tr>\n<tr>\n<td>Critique<\/td>\n<td>1 heure par jour ouvrable<\/td>\n<td>4 heures par jour ouvrable<\/td>\n<td>Le vendeur s'efforcera de fournir une solution de contournement dans les deux jours ouvrables et de r\u00e9soudre le d\u00e9faut dans les dix jours ouvrables.<\/td>\n<\/tr>\n<tr>\n<td>Principale<\/td>\n<td>1 jour ouvrable<\/td>\n<td>3 jours ouvrables<\/td>\n<td>Le vendeur s'efforcera de r\u00e9soudre le d\u00e9faut dans un d\u00e9lai de 4 jours ouvrables.<\/td>\n<\/tr>\n<tr>\n<td>Mineur<\/td>\n<td>2 jours ouvrables<\/td>\n<td>6 jours ouvrables<\/td>\n<td>Le vendeur fera des efforts raisonnables pour r\u00e9soudre le d\u00e9faut dans un d\u00e9lai de 15 jours ouvrables.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>Toutes les questions sont trait\u00e9es comme \u201cmineures\u201d.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Les d\u00e9lais susmentionn\u00e9s entrent en vigueur d\u00e8s que le client envoie une demande de services \u00e9crite \u00e0 laquelle sont jointes toutes les informations n\u00e9cessaires et appropri\u00e9es pour la reproductibilit\u00e9 des d\u00e9fauts.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>19. Responsabilit\u00e9s du fournisseur :<\/h4>\n<ol>\n<li>Le vendeur r\u00e9pond aux demandes de service en fonction de la priorit\u00e9 qui leur a \u00e9t\u00e9 attribu\u00e9e et dans les d\u00e9lais pr\u00e9vus par le pr\u00e9sent document.<\/li>\n<li>Le vendeur prend des mesures pour faire remonter, diagnostiquer et r\u00e9soudre les d\u00e9fauts de mani\u00e8re appropri\u00e9e et en temps utile, y compris l'affectation d'un nombre suffisant de personnel qualifi\u00e9 et la collecte des informations n\u00e9cessaires. et<\/li>\n<li>Le vendeur maintient \u00e0 tout moment une communication claire et opportune avec le client.<\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"NAVORI TERMS OF SERVICES Latest update: 23\/07\/2024 These Terms of Services (the \u201cTerms\u201d) are between the entity identified in an Order Form or which is provided with an Activation Code by a Reseller (\u201cCustomer\u201d; \u201cyou\u201d) and the Navori Contracting Entity. These Terms are effective upon (i) the purchase of the Navori Software Licence through an [...]","protected":false},"author":1,"featured_media":54308,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"dss.php","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-45676","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>General Terms and Conditions - Navori - Navori Labs<\/title>\n<meta name=\"description\" content=\"Navori Labs General Terms and Conditions. These general terms and conditions are legally binding agreement between Navori and the customer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/navori.com\/fr\/terms-of-services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General Terms and Conditions - Navori\" \/>\n<meta property=\"og:description\" content=\"Navori Labs General Terms and Conditions. These general terms and conditions are legally binding agreement between Navori and the customer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/navori.com\/fr\/terms-of-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Navori Labs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NavoriLabs\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T15:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/navori.com\/wp-content\/uploads\/2023\/10\/ServerRequirements.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@navori\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/\"},\"author\":{\"name\":\"navoriwebman1\",\"@id\":\"https:\\\/\\\/navori.com\\\/#\\\/schema\\\/person\\\/3de28eca2f1bad61c026c3bfcbedc0d0\"},\"headline\":\"General Terms and Conditions &#8211; Navori\",\"datePublished\":\"2023-10-18T13:05:44+00:00\",\"dateModified\":\"2025-11-06T15:08:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/\"},\"wordCount\":4857,\"publisher\":{\"@id\":\"https:\\\/\\\/navori.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/navori.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ServerRequirements.webp\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/\",\"url\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/\",\"name\":\"General Terms and Conditions - Navori - Navori Labs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/navori.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/navori.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ServerRequirements.webp\",\"datePublished\":\"2023-10-18T13:05:44+00:00\",\"dateModified\":\"2025-11-06T15:08:15+00:00\",\"description\":\"Navori Labs General Terms and Conditions. These general terms and conditions are legally binding agreement between Navori and the customer\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/navori.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ServerRequirements.webp\",\"contentUrl\":\"https:\\\/\\\/navori.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ServerRequirements.webp\",\"width\":960,\"height\":540,\"caption\":\"ServerRequirements\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/navori.com\\\/terms-of-services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/navori.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General Terms and Conditions &#8211; Navori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/navori.com\\\/#website\",\"url\":\"https:\\\/\\\/navori.com\\\/\",\"name\":\"Navori Labs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/navori.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/navori.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/navori.com\\\/#organization\",\"name\":\"Navori Labs\",\"url\":\"https:\\\/\\\/navori.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/navori.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/navori.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/NAVORI-logo.svg\",\"contentUrl\":\"https:\\\/\\\/navori.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/NAVORI-logo.svg\",\"width\":120,\"height\":19,\"caption\":\"Navori Labs\"},\"image\":{\"@id\":\"https:\\\/\\\/navori.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NavoriLabs\",\"https:\\\/\\\/x.com\\\/navori\",\"https:\\\/\\\/www.instagram.com\\\/navorilabs\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/navori-sa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NavoriQL\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/navori.com\\\/#\\\/schema\\\/person\\\/3de28eca2f1bad61c026c3bfcbedc0d0\",\"name\":\"navoriwebman1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b547b91e1c1c1bbaf0c28a3b85ef79f28f971c49b2650159ba15d821147fcde?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b547b91e1c1c1bbaf0c28a3b85ef79f28f971c49b2650159ba15d821147fcde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b547b91e1c1c1bbaf0c28a3b85ef79f28f971c49b2650159ba15d821147fcde?s=96&d=mm&r=g\",\"caption\":\"navoriwebman1\"},\"sameAs\":[\"https:\\\/\\\/navori.com\"],\"url\":\"https:\\\/\\\/navori.com\\\/fr\\\/author\\\/navoriwebman1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales d'utilisation - Navori - Navori Labs","description":"Conditions g\u00e9n\u00e9rales de Navori Labs. Ces conditions g\u00e9n\u00e9rales constituent un accord juridiquement contraignant entre Navori et le client.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/navori.com\/fr\/terms-of-services\/","og_locale":"fr_FR","og_type":"article","og_title":"General Terms and Conditions - Navori","og_description":"Navori Labs General Terms and Conditions. These general terms and conditions are legally binding agreement between Navori and the customer","og_url":"https:\/\/navori.com\/fr\/terms-of-services\/","og_site_name":"Navori Labs","article_publisher":"https:\/\/www.facebook.com\/NavoriLabs","article_modified_time":"2025-11-06T15:08:15+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/navori.com\/wp-content\/uploads\/2023\/10\/ServerRequirements.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@navori","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/navori.com\/terms-of-services\/#article","isPartOf":{"@id":"https:\/\/navori.com\/terms-of-services\/"},"author":{"name":"navoriwebman1","@id":"https:\/\/navori.com\/#\/schema\/person\/3de28eca2f1bad61c026c3bfcbedc0d0"},"headline":"General Terms and Conditions &#8211; Navori","datePublished":"2023-10-18T13:05:44+00:00","dateModified":"2025-11-06T15:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/navori.com\/terms-of-services\/"},"wordCount":4857,"publisher":{"@id":"https:\/\/navori.com\/#organization"},"image":{"@id":"https:\/\/navori.com\/terms-of-services\/#primaryimage"},"thumbnailUrl":"https:\/\/navori.com\/wp-content\/uploads\/2023\/10\/ServerRequirements.webp","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/navori.com\/terms-of-services\/","url":"https:\/\/navori.com\/terms-of-services\/","name":"Conditions g\u00e9n\u00e9rales d'utilisation - Navori - Navori Labs","isPartOf":{"@id":"https:\/\/navori.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/navori.com\/terms-of-services\/#primaryimage"},"image":{"@id":"https:\/\/navori.com\/terms-of-services\/#primaryimage"},"thumbnailUrl":"https:\/\/navori.com\/wp-content\/uploads\/2023\/10\/ServerRequirements.webp","datePublished":"2023-10-18T13:05:44+00:00","dateModified":"2025-11-06T15:08:15+00:00","description":"Conditions g\u00e9n\u00e9rales de Navori Labs. Ces conditions g\u00e9n\u00e9rales constituent un accord juridiquement contraignant entre Navori et le client.","breadcrumb":{"@id":"https:\/\/navori.com\/terms-of-services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/navori.com\/terms-of-services\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/navori.com\/terms-of-services\/#primaryimage","url":"https:\/\/navori.com\/wp-content\/uploads\/2023\/10\/ServerRequirements.webp","contentUrl":"https:\/\/navori.com\/wp-content\/uploads\/2023\/10\/ServerRequirements.webp","width":960,"height":540,"caption":"ServerRequirements"},{"@type":"BreadcrumbList","@id":"https:\/\/navori.com\/terms-of-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/navori.com\/"},{"@type":"ListItem","position":2,"name":"General Terms and Conditions &#8211; Navori"}]},{"@type":"WebSite","@id":"https:\/\/navori.com\/#website","url":"https:\/\/navori.com\/","name":"Navori Labs","description":"","publisher":{"@id":"https:\/\/navori.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/navori.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/navori.com\/#organization","name":"Navori Labs","url":"https:\/\/navori.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/navori.com\/#\/schema\/logo\/image\/","url":"https:\/\/navori.com\/wp-content\/uploads\/2024\/04\/NAVORI-logo.svg","contentUrl":"https:\/\/navori.com\/wp-content\/uploads\/2024\/04\/NAVORI-logo.svg","width":120,"height":19,"caption":"Navori Labs"},"image":{"@id":"https:\/\/navori.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NavoriLabs","https:\/\/x.com\/navori","https:\/\/www.instagram.com\/navorilabs","https:\/\/www.linkedin.com\/company\/navori-sa","https:\/\/www.youtube.com\/user\/NavoriQL"]},{"@type":"Person","@id":"https:\/\/navori.com\/#\/schema\/person\/3de28eca2f1bad61c026c3bfcbedc0d0","name":"navoriwebman1","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b547b91e1c1c1bbaf0c28a3b85ef79f28f971c49b2650159ba15d821147fcde?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b547b91e1c1c1bbaf0c28a3b85ef79f28f971c49b2650159ba15d821147fcde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b547b91e1c1c1bbaf0c28a3b85ef79f28f971c49b2650159ba15d821147fcde?s=96&d=mm&r=g","caption":"navoriwebman1"},"sameAs":["https:\/\/navori.com"],"url":"https:\/\/navori.com\/fr\/author\/navoriwebman1\/"}]}},"_links":{"self":[{"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/pages\/45676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/comments?post=45676"}],"version-history":[{"count":0,"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/pages\/45676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/media\/54308"}],"wp:attachment":[{"href":"https:\/\/navori.com\/fr\/wp-json\/wp\/v2\/media?parent=45676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}